{"id":29844,"date":"2024-02-23T15:39:04","date_gmt":"2024-02-23T14:39:04","guid":{"rendered":"https:\/\/yoann-conte.com\/?post_type=product&#038;p=29844"},"modified":"2025-04-02T14:14:30","modified_gmt":"2025-04-02T12:14:30","slug":"selection-de-fromages-pain-de-campagne","status":"publish","type":"product","link":"https:\/\/yoann-conte.com\/es\/producto\/selection-de-fromages-pain-de-campagne\/","title":{"rendered":"Selecci\u00f3n de quesos, pan de pay\u00e9s"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false},"product_brand":[],"product_cat":[44],"product_tag":[],"class_list":["post-29844","product","type-product","status-publish","product_cat-nos-desserts","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e9lection de fromages, pain de campagne - Yoann Conte, un lieu embl\u00e9matique \u00e0 Veyrier-du-lac, o\u00f9 se rencontrent l&#039;\u00e9l\u00e9gance de notre h\u00f4tel 5 \u00e9toiles et la cr\u00e9ativit\u00e9 d\u2019une cuisine gastronomique 2 \u00e9toiles, au c\u0153ur d\u2019un cadre naturel exceptionnel.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yoann-conte.com\/es\/producto\/selection-de-fromages-pain-de-campagne\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9lection de fromages, pain de campagne - Yoann Conte, un lieu embl\u00e9matique \u00e0 Veyrier-du-lac, o\u00f9 se rencontrent l&#039;\u00e9l\u00e9gance de notre h\u00f4tel 5 \u00e9toiles et la cr\u00e9ativit\u00e9 d\u2019une cuisine gastronomique 2 \u00e9toiles, au c\u0153ur d\u2019un cadre naturel exceptionnel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yoann-conte.com\/es\/producto\/selection-de-fromages-pain-de-campagne\/\" \/>\n<meta property=\"og:site_name\" content=\"Yoann Conte, un lieu embl\u00e9matique \u00e0 Veyrier-du-lac, o\u00f9 se rencontrent l&#039;\u00e9l\u00e9gance de notre h\u00f4tel 5 \u00e9toiles et la cr\u00e9ativit\u00e9 d\u2019une cuisine gastronomique 2 \u00e9toiles, au c\u0153ur d\u2019un cadre naturel exceptionnel.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T12:14:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yoann-conte.com\\\/produit\\\/selection-de-fromages-pain-de-campagne\\\/\",\"url\":\"https:\\\/\\\/yoann-conte.com\\\/produit\\\/selection-de-fromages-pain-de-campagne\\\/\",\"name\":\"S\u00e9lection de fromages, pain de campagne - Yoann Conte, un lieu embl\u00e9matique \u00e0 Veyrier-du-lac, o\u00f9 se rencontrent l&#039;\u00e9l\u00e9gance de notre h\u00f4tel 5 \u00e9toiles et la cr\u00e9ativit\u00e9 d\u2019une cuisine gastronomique 2 \u00e9toiles, au c\u0153ur d\u2019un cadre naturel exceptionnel.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yoann-conte.com\\\/#website\"},\"datePublished\":\"2024-02-23T14:39:04+00:00\",\"dateModified\":\"2025-04-02T12:14:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yoann-conte.com\\\/produit\\\/selection-de-fromages-pain-de-campagne\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yoann-conte.com\\\/produit\\\/selection-de-fromages-pain-de-campagne\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yoann-conte.com\\\/produit\\\/selection-de-fromages-pain-de-campagne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/yoann-conte.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/yoann-conte.com\\\/es\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00e9lection de fromages, pain de campagne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yoann-conte.com\\\/#website\",\"url\":\"https:\\\/\\\/yoann-conte.com\\\/\",\"name\":\"Yoann Conte, un lieu embl\u00e9matique \u00e0 Veyrier-du-lac, o\u00f9 se rencontrent l&#039;\u00e9l\u00e9gance de notre h\u00f4tel 5 \u00e9toiles et la cr\u00e9ativit\u00e9 d\u2019une cuisine gastronomique 2 \u00e9toiles, au c\u0153ur d\u2019un cadre naturel exceptionnel.\",\"description\":\"Restaurant gastronomique \u00e0 Annecy, Yoann Conte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yoann-conte.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Selecci\u00f3n de quesos, pan de campo - Yoann Conte, un lugar emblem\u00e1tico en Veyrier-du-lac, donde se unen la elegancia de nuestro hotel de 5 estrellas y la creatividad de una cocina gastron\u00f3mica de 2 estrellas, en el coraz\u00f3n de un entorno natural excepcional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yoann-conte.com\/es\/producto\/selection-de-fromages-pain-de-campagne\/","og_locale":"es_ES","og_type":"article","og_title":"S\u00e9lection de fromages, pain de campagne - Yoann Conte, un lieu embl\u00e9matique \u00e0 Veyrier-du-lac, o\u00f9 se rencontrent l&#039;\u00e9l\u00e9gance de notre h\u00f4tel 5 \u00e9toiles et la cr\u00e9ativit\u00e9 d\u2019une cuisine gastronomique 2 \u00e9toiles, au c\u0153ur d\u2019un cadre naturel exceptionnel.","og_url":"https:\/\/yoann-conte.com\/es\/producto\/selection-de-fromages-pain-de-campagne\/","og_site_name":"Yoann Conte, un lieu embl\u00e9matique \u00e0 Veyrier-du-lac, o\u00f9 se rencontrent l&#039;\u00e9l\u00e9gance de notre h\u00f4tel 5 \u00e9toiles et la cr\u00e9ativit\u00e9 d\u2019une cuisine gastronomique 2 \u00e9toiles, au c\u0153ur d\u2019un cadre naturel exceptionnel.","article_modified_time":"2025-04-02T12:14:30+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/yoann-conte.com\/produit\/selection-de-fromages-pain-de-campagne\/","url":"https:\/\/yoann-conte.com\/produit\/selection-de-fromages-pain-de-campagne\/","name":"Selecci\u00f3n de quesos, pan de campo - Yoann Conte, un lugar emblem\u00e1tico en Veyrier-du-lac, donde se unen la elegancia de nuestro hotel de 5 estrellas y la creatividad de una cocina gastron\u00f3mica de 2 estrellas, en el coraz\u00f3n de un entorno natural excepcional.","isPartOf":{"@id":"https:\/\/yoann-conte.com\/#website"},"datePublished":"2024-02-23T14:39:04+00:00","dateModified":"2025-04-02T12:14:30+00:00","breadcrumb":{"@id":"https:\/\/yoann-conte.com\/produit\/selection-de-fromages-pain-de-campagne\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yoann-conte.com\/produit\/selection-de-fromages-pain-de-campagne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/yoann-conte.com\/produit\/selection-de-fromages-pain-de-campagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/yoann-conte.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/yoann-conte.com\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"S\u00e9lection de fromages, pain de campagne"}]},{"@type":"WebSite","@id":"https:\/\/yoann-conte.com\/#website","url":"https:\/\/yoann-conte.com\/","name":"Yoann Conte, un lugar emblem\u00e1tico en Veyrier-du-lac, donde se unen la elegancia de nuestro hotel de 5 estrellas y la creatividad de una cocina gastron\u00f3mica de 2 estrellas, en el coraz\u00f3n de un entorno natural excepcional.","description":"Restaurante gastron\u00f3mico en Annecy, Yoann Conte","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yoann-conte.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/yoann-conte.com\/es\/wp-json\/wp\/v2\/product\/29844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yoann-conte.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/yoann-conte.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/yoann-conte.com\/es\/wp-json\/wp\/v2\/media?parent=29844"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/yoann-conte.com\/es\/wp-json\/wp\/v2\/product_brand?post=29844"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/yoann-conte.com\/es\/wp-json\/wp\/v2\/product_cat?post=29844"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/yoann-conte.com\/es\/wp-json\/wp\/v2\/product_tag?post=29844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}